{"id":459,"date":"2026-03-30T09:19:03","date_gmt":"2026-03-30T07:19:03","guid":{"rendered":"https:\/\/drogasotu.com\/?p=459"},"modified":"2026-03-30T09:22:49","modified_gmt":"2026-03-30T07:22:49","slug":"nuestra-unidad-movil-no-para-cronica-de-un-trimestre-de-prevencion-en-la-comunidad-de-madrid","status":"publish","type":"post","link":"https:\/\/drogasotu.com\/index.php\/2026\/03\/30\/nuestra-unidad-movil-no-para-cronica-de-un-trimestre-de-prevencion-en-la-comunidad-de-madrid\/","title":{"rendered":"\u00a1Nuestra unidad m\u00f3vil no para! Cr\u00f3nica de un trimestre de prevenci\u00f3n en la Comunidad de Madrid"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p id=\"p-rc_6a867c3bd6747ac2-19\">El servicio itinerante\u00a0<strong>\u00abDrogas o T\u00fa\u00bb<\/strong>\u00a0ha completado un inicio de a\u00f1o 2026 de lo m\u00e1s intenso, recorriendo decenas de municipios y centros educativos para llevar la prevenci\u00f3n de adicciones directamente a donde est\u00e1n los j\u00f3venes.\u00a0Desde las aulas de los institutos hasta las plazas m\u00e1s emblem\u00e1ticas, nuestro equipo ha trabajado sin descanso para fomentar el pensamiento cr\u00edtico y los h\u00e1bitos saludables.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Educaci\u00f3n en las aulas: De Majadahonda a Legan\u00e9s<\/strong><\/h3>\n\n\n\n<p id=\"p-rc_6a867c3bd6747ac2-20\">Durante estas \u00faltimas semanas, nuestra prioridad ha sido el entorno escolar.\u00a0Hemos visitado numerosos centros en\u00a0<strong>Majadahonda<\/strong>, como el\u00a0<strong>IES Leonardo da Vinci<\/strong>, el\u00a0<strong>IES Margarita Salas<\/strong>\u00a0y el\u00a0<strong>IES Jos\u00e9 Saramago<\/strong>, impartiendo charlas adaptadas a alumnos de ESO, Bachillerato y Formaci\u00f3n Profesional.<\/p>\n\n\n\n<p id=\"p-rc_6a867c3bd6747ac2-21\">Tambi\u00e9n hemos tenido una presencia muy fuerte en&nbsp;<strong>Legan\u00e9s<\/strong>, donde centros como el&nbsp;<strong>IES Siglo XXI<\/strong>,&nbsp;<strong>IES Rafael Fr\u00fchbeck de Burgos<\/strong>&nbsp;y el&nbsp;<strong>IES Enrique Tierno Galv\u00e1n<\/strong>&nbsp;nos abrieron sus puertas para trabajar con grupos de 2\u00ba y 3\u00ba de la ESO<sup><\/sup><sup><\/sup><sup><\/sup><sup><\/sup><sup><\/sup><sup><\/sup><sup><\/sup><sup><\/sup><sup><\/sup>.&nbsp;En cada sesi\u00f3n, el objetivo es claro: desmontar mitos y ofrecer herramientas reales frente al consumo de sustancias<sup><\/sup><sup><\/sup><sup><\/sup><sup><\/sup>.+4<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Compromiso institucional y cercan\u00eda<\/strong><\/h3>\n\n\n\n<p>La labor de la unidad m\u00f3vil ha contado con el respaldo de diversas autoridades locales que han querido conocer de primera mano nuestra metodolog\u00eda. Entre las visitas m\u00e1s destacadas de este trimestre se encuentran:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Miguel \u00c1ngel Recuenco<\/strong>, Alcalde de Legan\u00e9s, quien nos acompa\u00f1\u00f3 en el Parque de Seraf\u00edn D\u00edez Ant\u00f3n.<\/li>\n\n\n\n<li><strong>Roc\u00edo Sara Garc\u00eda Alc\u00e1ntara<\/strong>, Alcaldesa de Alcobendas, durante nuestra estancia en el IES Gloria Fuertes.<\/li>\n\n\n\n<li><strong>Alessandra Romero Guijarro<\/strong>, Concejala de Salud P\u00fablica de Alcorc\u00f3n, presente en las sesiones de los institutos Los Castillos y Luis Bu\u00f1uel.<\/li>\n<\/ul>\n\n\n\n<p id=\"p-rc_6a867c3bd6747ac2-25\">Estas visitas refuerzan la importancia de la colaboraci\u00f3n entre las instituciones y el servicio de prevenci\u00f3n para llegar a cada rinc\u00f3n de la regi\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fines de semana de puertas abiertas<\/strong><\/h3>\n\n\n\n<p id=\"p-rc_6a867c3bd6747ac2-26\">No solo estamos en los institutos.\u00a0Los fines de semana hemos convertido plazas y parques en espacios de encuentro para familias y j\u00f3venes.\u00a0Lugares como la\u00a0<strong>Plaza de Espa\u00f1a<\/strong>\u00a0en Madrid, el\u00a0<strong>Estadio Metropolitano<\/strong>, la\u00a0<strong>Pista de patinaje de Madrid R\u00edo<\/strong>\u00a0y la zona de ocio de\u00a0<strong>Pozuelo de Alarc\u00f3n<\/strong>\u00a0han sido testigos de nuestras jornadas de puertas abiertas, facilitando el acceso a la informaci\u00f3n de una manera l\u00fadica y cercana.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Desmontando mitos en las redes<\/strong><\/h3>\n\n\n\n<p>Paralelamente a la actividad presencial, nuestra comunidad digital sigue creciendo. Hemos mantenido activos nuestros perfiles con publicaciones clave sobre:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mitos sobre la pornograf\u00eda y el \u00f3xido nitroso<\/li>\n\n\n\n<li>Informaci\u00f3n sobre el uso de cachimbas y los riesgos de TikTok<\/li>\n\n\n\n<li>Especiales por el D\u00eda Internacional de la Mujer y el D\u00eda de la Paz<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>\u00bfQuieres que visitemos tu municipio o centro escolar?<\/strong>&nbsp;Mantente atento a nuestras redes sociales para conocer nuestra ubicaci\u00f3n diaria y no pierdas la oportunidad de subirte a la unidad. \u00a1Te esperamos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El servicio itinerante\u00a0\u00abDrogas o T\u00fa\u00bb\u00a0ha completado un inicio de a\u00f1o 2026 de lo m\u00e1s intenso, recorriendo decenas de municipios y<\/p>\n","protected":false},"author":1,"featured_media":460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-_"],"uagb_featured_image_src":{"full":["https:\/\/drogasotu.com\/wp-content\/uploads\/2026\/03\/22-03-2026-PLAZA-DE-ESPANA-e1774855136583.jpeg",1536,717,false],"thumbnail":["https:\/\/drogasotu.com\/wp-content\/uploads\/2026\/03\/22-03-2026-PLAZA-DE-ESPANA-e1774855136583-150x150.jpeg",150,150,true],"medium":["https:\/\/drogasotu.com\/wp-content\/uploads\/2026\/03\/22-03-2026-PLAZA-DE-ESPANA-e1774855136583-300x140.jpeg",300,140,true],"medium_large":["https:\/\/drogasotu.com\/wp-content\/uploads\/2026\/03\/22-03-2026-PLAZA-DE-ESPANA-e1774855136583-768x359.jpeg",768,359,true],"large":["https:\/\/drogasotu.com\/wp-content\/uploads\/2026\/03\/22-03-2026-PLAZA-DE-ESPANA-e1774855136583-1024x478.jpeg",1024,478,true],"1536x1536":["https:\/\/drogasotu.com\/wp-content\/uploads\/2026\/03\/22-03-2026-PLAZA-DE-ESPANA-e1774855136583.jpeg",1536,717,false],"2048x2048":["https:\/\/drogasotu.com\/wp-content\/uploads\/2026\/03\/22-03-2026-PLAZA-DE-ESPANA-e1774855136583.jpeg",1536,717,false]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/drogasotu.com\/index.php\/author\/jon_bhsl7b9f\/"},"uagb_comment_info":0,"uagb_excerpt":"El servicio itinerante\u00a0\u00abDrogas o T\u00fa\u00bb\u00a0ha completado un inicio de a\u00f1o 2026 de lo m\u00e1s intenso, recorriendo decenas de municipios y","_links":{"self":[{"href":"https:\/\/drogasotu.com\/index.php\/wp-json\/wp\/v2\/posts\/459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drogasotu.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/drogasotu.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/drogasotu.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/drogasotu.com\/index.php\/wp-json\/wp\/v2\/comments?post=459"}],"version-history":[{"count":2,"href":"https:\/\/drogasotu.com\/index.php\/wp-json\/wp\/v2\/posts\/459\/revisions"}],"predecessor-version":[{"id":462,"href":"https:\/\/drogasotu.com\/index.php\/wp-json\/wp\/v2\/posts\/459\/revisions\/462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drogasotu.com\/index.php\/wp-json\/wp\/v2\/media\/460"}],"wp:attachment":[{"href":"https:\/\/drogasotu.com\/index.php\/wp-json\/wp\/v2\/media?parent=459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/drogasotu.com\/index.php\/wp-json\/wp\/v2\/categories?post=459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/drogasotu.com\/index.php\/wp-json\/wp\/v2\/tags?post=459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}